{"id":80,"date":"2022-04-04T08:53:34","date_gmt":"2022-04-04T08:53:34","guid":{"rendered":"https:\/\/greenly-demo.pbminfotech.com\/elementor-datasite\/?page_id=10818"},"modified":"2023-09-26T06:08:17","modified_gmt":"2023-09-26T06:08:17","slug":"homepage-4","status":"publish","type":"page","link":"https:\/\/wilpowgroup.com\/","title":{"rendered":"HOME"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"80\" class=\"elementor elementor-80\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e816a76 cspt-col-stretched-none cspt-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e816a76\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-25c84a1 cspt-bg-color-over-image\" data-id=\"25c84a1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db7584a elementor-widget elementor-widget-slider_revolution\" data-id=\"db7584a\" data-element_type=\"widget\" data-widget_type=\"slider_revolution.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"wp-block-themepunch-revslider\">\n\t\t\t<!-- START Slider 1 REVOLUTION SLIDER 6.7.18 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_1_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_1_1\" style=\"\" data-version=\"6.7.18\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-1\" data-title=\"Slide\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/wilpowgroup.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"HOME\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/wilpowgroup.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-1-layer-0\" \n\t\t\t\t\t\t\t\tdata-type=\"shape\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:-196px;y:-131px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:2508;h:761;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;background-color:rgba(0,0,0,0.7);\"\n\t\t\t\t\t\t\t> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-1-layer-1\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"#fff\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:293px;y:187px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:75;l:88;ls:2;fw:700;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:752px;minh:0;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;font-family:'Roboto';\"\n\t\t\t\t\t\t\t>We offer Reliable & swift delivery. \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-1-layer-2\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:-112px;y:-88px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:1516px;h:758px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;\"\n\t\t\t\t\t\t\t><img fetchpriority=\"high\" decoding=\"async\" src=\"\/\/wilpowgroup.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1200\" height=\"600\" data-lazyload=\"\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/07\/wilpo-slider1-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-1-layer-3\" \n\t\t\t\t\t\t\t\tdata-type=\"shape\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:-160px;y:-38px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:1638px;h:743px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;background-color:rgba(0,0,0,0.9);\"\n\t\t\t\t\t\t\t><rs-bg-elem style=\"background: url('\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/07\/wilpow-slider.jpg') no-repeat center center; background-size: cover;\"><\/rs-bg-elem>\n \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-3\" data-title=\"Slide\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/wilpowgroup.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"Slide\" title=\"HOME\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/wilpowgroup.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/transparent.png\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-3-layer-0\" \n\t\t\t\t\t\t\t\tdata-type=\"shape\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:-196px;y:-131px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:2508;h:761;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;background-color:rgba(0,0,0,0.7);\"\n\t\t\t\t\t\t\t> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-3-layer-1\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"#fff\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:293px;y:187px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:75;l:88;ls:2;fw:700;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:752px;minh:0;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;font-family:'Roboto';\"\n\t\t\t\t\t\t\t>Welcome to Wilpow Group \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-3-layer-2\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:-112px;y:-88px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:1516px;h:758px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;\"\n\t\t\t\t\t\t\t><img fetchpriority=\"high\" decoding=\"async\" src=\"\/\/wilpowgroup.com\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"1200\" height=\"600\" data-lazyload=\"\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/07\/wilpo-slider1-1.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-3-layer-3\" \n\t\t\t\t\t\t\t\tdata-type=\"shape\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:-160px;y:-38px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:1638px;h:743px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;background-color:rgba(0,0,0,0.9);\"\n\t\t\t\t\t\t\t><rs-bg-elem style=\"background: url('\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/08\/wilpow-slide2.png') no-repeat center center; background-size: cover;\"><\/rs-bg-elem>\n \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_1_1',rl:[1240,1024,778,480],el:[600],gw:[1240],gh:[600],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider11\"]!==undefined) {window.RS_MODULES.modules[\"revslider11\"].once = false;window.revapi1 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-751fb1a1 cspt-steps-counter cspt-col-stretched-none cspt-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"751fb1a1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7df9534c cspt-bg-color-over-image\" data-id=\"7df9534c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-549fed87 cspt-align-left elementor-widget elementor-widget-cspt_multiple_icon_heading\" data-id=\"549fed87\" data-element_type=\"widget\" data-widget_type=\"cspt_multiple_icon_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"creativesplanet-element creativesplanet-element-miconheading cspt-element-miconheading-style-7 creativesplanet-element-viewtype-row-column\" data-show=\"3\" data-columns=\"4\" data-loop=\"false\" data-autoplay=\"false\" data-center=\"false\" data-nav=\"false\" data-dots=\"false\" data-autoplayspeed=\"1000\" data-margin=\"\"><div class=\"creativesplanet-element-inner\">\n\t\t<div class=\"cspt-ele-header-area\">\n\t\t\t\t<div class=\"cspt-heading-subheading left-align \"><\/div>\t\t<\/div>\n\n\t\t<div class=\"cspt-element-posts-wrapper row multi-columns-row\">\n\n\t\t<div class=\"cspt-ele cspt-miconheading-ele col-md-6 col-lg-3 \"><div class=\"cspt-ihbox cspt-ihbox-style-7\"><div class=\"cspt-ihbox cspt-ihbox-style- \">\n\t<div class=\"cspt-ihbox-icon\"><div class=\"cspt-ihbox-icon-wrapper\"><i class=\"far fa-paper-plane\"><\/i><\/div><\/div>\t<div class=\"cspt-ihbox-contents\">\n\t\t<h2 class=\"cspt-element-title\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\tExport\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"cspt-heading-desc\">Welcome to our world of exporting top-quality products worldwide. If you seek the best products delivered on time, you've come to the right place!<\/div>\t\t\t<\/div><!-- .cspt-ihbox-contents -->\n<\/div>\n<\/div><\/div><div class=\"cspt-ele cspt-miconheading-ele col-md-6 col-lg-3 \"><div class=\"cspt-ihbox cspt-ihbox-style-7\"><div class=\"cspt-ihbox cspt-ihbox-style- \">\n\t<div class=\"cspt-ihbox-icon\"><div class=\"cspt-ihbox-icon-wrapper\"><i class=\"fas fa-angle-double-down\"><\/i><\/div><\/div>\t<div class=\"cspt-ihbox-contents\">\n\t\t<h2 class=\"cspt-element-title\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\tImport agent\n(for foreign client)\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"cspt-heading-desc\">We help foreign company to introduce his best quality product in India and help them to find local partners in India<\/div>\t\t\t<\/div><!-- .cspt-ihbox-contents -->\n<\/div>\n<\/div><\/div><div class=\"cspt-ele cspt-miconheading-ele col-md-6 col-lg-3 \"><div class=\"cspt-ihbox cspt-ihbox-style-7\"><div class=\"cspt-ihbox cspt-ihbox-style- \">\n\t<div class=\"cspt-ihbox-icon\"><div class=\"cspt-ihbox-icon-wrapper\"><i class=\"fab fa-battle-net\"><\/i><\/div><\/div>\t<div class=\"cspt-ihbox-contents\">\n\t\t<h2 class=\"cspt-element-title\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\tSourcing Agent\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"cspt-heading-desc\">We are working as local partner of our foreign client to source best quality product from India as per client requirement and Specification<\/div>\t\t\t<\/div><!-- .cspt-ihbox-contents -->\n<\/div>\n<\/div><\/div><div class=\"cspt-ele cspt-miconheading-ele col-md-6 col-lg-3 \"><div class=\"cspt-ihbox cspt-ihbox-style-7\"><div class=\"cspt-ihbox cspt-ihbox-style- \">\n\t<div class=\"cspt-ihbox-icon\"><div class=\"cspt-ihbox-icon-wrapper\"><i class=\"fas fa-award\"><\/i><\/div><\/div>\t<div class=\"cspt-ihbox-contents\">\n\t\t<h2 class=\"cspt-element-title\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\tTraining &amp; consultancy\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"cspt-heading-desc\">Unlock the potential of global business with our Practical Export-Import Training. We're dedicated to making international trade easy and accessible for all.<\/div>\t\t\t<\/div><!-- .cspt-ihbox-contents -->\n<\/div>\n<\/div><\/div>\n\t\t<\/div>\n\n\t\t<\/div><!-- .creativesplanet-element-inner -->   <\/div><!-- .creativesplanet-element -->  \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-be1fb37 elementor-section-stretched cspt-col-stretched-none cspt-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"be1fb37\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e16d9ee cspt-bg-color-over-image\" data-id=\"e16d9ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96bab24 cspt-btn-shape-round cspt-btn-color-globalcolor cspt-btn-style-flat elementor-widget elementor-widget-button\" data-id=\"96bab24\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-419a44e8 cspt-align-left elementor-widget elementor-widget-cspt_heading\" data-id=\"419a44e8\" data-element_type=\"widget\" data-widget_type=\"cspt_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"cspt-heading-subheading left-align cspt-reverse-heading-yes\"><h4 class=\"cspt-element-subtitle\">\n\t\t\t\n\t\t\t\tOUR STORY\n\t\t\t\n\t\t\t<\/h4>\n\t\t<h2 class=\"cspt-element-title\">\n\t\t\t\n\t\t\t\tABOUT\nWILPOW GROUP\n\t\t\t\n\t\t\t<\/h2>\n\t\t<div class=\"cspt-heading-desc\"><P>Wilpo has successfully carved its own path, establishing a strong reputation and name for itself in the market. As prominent exporters, we take pride in offering a wide array of exquisite products, including Wooden Handicrafts, Wooden Items, Glass Items, Handmade Products, Photo Frames, Handmade Clothing, Decorative Products, and an impressive variety of Wooden Temples.<\/P>\n\n<P>Our products epitomize elegance, style, and superior quality, setting them apart in the industry. With a well-established global clientele, we have earned the trust of customers worldwide.<\/P>\n<\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7712472 cspt-bg-color-over-image\" data-id=\"7712472\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b34fe9f elementor-widget elementor-widget-image\" data-id=\"b34fe9f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/wilpowgroup.com\/wp-content\/uploads\/elementor\/thumbs\/man-walking-through-large-warehouse-storage-storehouse-center-using-tablet-control-distribution-scaled-qm5gywntyarady4135p6h7ogzz9zduxor7qvv2eo74.jpg\" title=\"man-walking-through-large-warehouse-storage-storehouse-center-using-tablet-control-distribution\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-951179c cspt-col-stretched-none cspt-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"951179c\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b04ca15 cspt-bg-color-over-image\" data-id=\"b04ca15\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e29ed0 cspt-align-center elementor-widget elementor-widget-cspt_heading\" data-id=\"3e29ed0\" data-element_type=\"widget\" data-widget_type=\"cspt_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"cspt-heading-subheading center-align \"><h2 class=\"cspt-element-title\">\n\t\t\t\n\t\t\t\tWHAT WE EXPORT\n\t\t\t\n\t\t\t<\/h2>\n\t\t<h4 class=\"cspt-element-subtitle\">\n\t\t\t\n\t\t\t\tOUR PRODUCTS\n\t\t\t\n\t\t\t<\/h4>\n\t\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-807e4f1 cspt-col-stretched-none cspt-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"807e4f1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7ed2045 cspt-bg-color-over-image\" data-id=\"7ed2045\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c547255 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"c547255\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"288\" height=\"300\" src=\"https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/09\/Spices-PNG-Picture-288x300.png\" class=\"attachment-medium size-medium wp-image-878\" alt=\"\" srcset=\"https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/09\/Spices-PNG-Picture-288x300.png 288w, https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/09\/Spices-PNG-Picture.png 526w\" sizes=\"(max-width: 288px) 100vw, 288px\" data-id=\"878\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">SPICES PRODUCTS<\/h3><p class=\"elementor-image-box-description\">Spices, from plant parts like seeds, fruits, roots, and bark, enhance flavors and colors in cooking, distinct from herbs.\n<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e04f568 cspt-btn-color-blackish cspt-btn-shape-rounded elementor-align-center e-transform cspt-btn-style-flat elementor-widget elementor-widget-button\" data-id=\"e04f568\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scaleX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wilpowgroup.com\/index.php\/product-category\/spices-products\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-35c013f cspt-bg-color-over-image\" data-id=\"35c013f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6be6897 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"6be6897\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"768\" height=\"691\" src=\"https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/09\/fruits-1200x1080-1-768x691.png\" class=\"attachment-medium_large size-medium_large wp-image-881\" alt=\"\" srcset=\"https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/09\/fruits-1200x1080-1-768x691.png 768w, https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/09\/fruits-1200x1080-1-300x270.png 300w, https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/09\/fruits-1200x1080-1-1024x922.png 1024w, https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/09\/fruits-1200x1080-1-770x693.png 770w, https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/09\/fruits-1200x1080-1-600x540.png 600w, https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/09\/fruits-1200x1080-1.png 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-id=\"881\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">FRUITS & VEGITABLES<\/h3><p class=\"elementor-image-box-description\">Our selection comprises fresh and sanitary fruits and vegetables, brimming with crucial vitamins, minerals, and plant compounds.\n<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee8fa91 cspt-btn-color-blackish cspt-btn-shape-rounded elementor-align-center e-transform cspt-btn-style-flat elementor-widget elementor-widget-button\" data-id=\"ee8fa91\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scaleX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wilpowgroup.com\/index.php\/product-category\/fruits-vegetables\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-080ef68 cspt-bg-color-over-image\" data-id=\"080ef68\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8651af1 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8651af1\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"847\" height=\"847\" src=\"https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/09\/Grocery-Bag-PNG-Clipart-Background.png\" class=\"attachment-large size-large wp-image-885\" alt=\"\" srcset=\"https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/09\/Grocery-Bag-PNG-Clipart-Background.png 1000w, https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/09\/Grocery-Bag-PNG-Clipart-Background-300x300.png 300w, https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/09\/Grocery-Bag-PNG-Clipart-Background-150x150.png 150w, https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/09\/Grocery-Bag-PNG-Clipart-Background-768x768.png 768w, https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/09\/Grocery-Bag-PNG-Clipart-Background-770x770.png 770w, https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/09\/Grocery-Bag-PNG-Clipart-Background-600x600.png 600w, https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/09\/Grocery-Bag-PNG-Clipart-Background-100x100.png 100w\" sizes=\"(max-width: 847px) 100vw, 847px\" data-id=\"885\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">GROCERY PRODUCTS<\/h3><p class=\"elementor-image-box-description\">We offer a diverse range of grocery items, including dal, flours, and pulses, tailored to meet our valued customers' needs<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-456b186 cspt-btn-color-blackish cspt-btn-shape-rounded elementor-align-center e-transform cspt-btn-style-flat elementor-widget elementor-widget-button\" data-id=\"456b186\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scaleX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wilpowgroup.com\/index.php\/product-category\/grocery-products\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68bb1fb cspt-col-stretched-none cspt-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"68bb1fb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-63fc575 cspt-bg-color-over-image\" data-id=\"63fc575\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bab5d9 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1bab5d9\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"847\" height=\"635\" src=\"https:\/\/wilpowgroup.com\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2023-07-20-at-3.16.34-PM-1024x768.jpeg\" class=\"attachment-large size-large wp-image-368\" alt=\"\" srcset=\"https:\/\/wilpowgroup.com\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2023-07-20-at-3.16.34-PM-1024x768.jpeg 1024w, https:\/\/wilpowgroup.com\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2023-07-20-at-3.16.34-PM-600x450.jpeg 600w, https:\/\/wilpowgroup.com\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2023-07-20-at-3.16.34-PM-300x225.jpeg 300w, https:\/\/wilpowgroup.com\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2023-07-20-at-3.16.34-PM-768x576.jpeg 768w, https:\/\/wilpowgroup.com\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2023-07-20-at-3.16.34-PM-770x578.jpeg 770w, https:\/\/wilpowgroup.com\/wp-content\/uploads\/2018\/10\/WhatsApp-Image-2023-07-20-at-3.16.34-PM.jpeg 1280w\" sizes=\"(max-width: 847px) 100vw, 847px\" data-id=\"368\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">NAMKEEN & FROZEN<\/h3><p class=\"elementor-image-box-description\">Indian salted Namkeen has garnered global acclaim for its distinctive blend of sweet, salty, tangy, and spicy flavors\n\n<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e42140a cspt-btn-color-blackish cspt-btn-shape-rounded elementor-align-center e-transform cspt-btn-style-flat elementor-widget elementor-widget-button\" data-id=\"e42140a\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scaleX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wilpowgroup.com\/index.php\/product-category\/namekeen-frozen\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3e5c4d6 cspt-bg-color-over-image\" data-id=\"3e5c4d6\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd0b093 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"bd0b093\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/07\/28086-8-jewellery-necklace-image-thumb.png\" class=\"attachment-1536x1536 size-1536x1536 wp-image-644\" alt=\"\" srcset=\"https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/07\/28086-8-jewellery-necklace-image-thumb.png 200w, https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/07\/28086-8-jewellery-necklace-image-thumb-100x100.png 100w, https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/07\/28086-8-jewellery-necklace-image-thumb-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" data-id=\"644\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">ARTIFICIAL JEWELLERY<\/h3><p class=\"elementor-image-box-description\">Artificial jewelry, often called costume, imitation, or fashion jewelry, is cherished by many for its affordability and striking resemblance to genuine pieces.<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8e0be4 cspt-btn-color-blackish cspt-btn-shape-rounded elementor-align-center e-transform cspt-btn-style-flat elementor-widget elementor-widget-button\" data-id=\"e8e0be4\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scaleX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b8700f4 cspt-bg-color-over-image\" data-id=\"b8700f4\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-166d5d2 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"166d5d2\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/07\/copper-bottle-sub-category.jpg\" class=\"attachment-large size-large wp-image-657\" alt=\"\" srcset=\"https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/07\/copper-bottle-sub-category.jpg 600w, https:\/\/wilpowgroup.com\/wp-content\/uploads\/2023\/07\/copper-bottle-sub-category-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" data-id=\"657\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">COPPER PRODUCTS<\/h3><p class=\"elementor-image-box-description\">Copper is a vital nutrient essential for the body, aiding in the formation of red blood cells, the maintenance of healthy bones, blood vessels, nerves, and supporting immune function<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b9c5ac cspt-btn-color-blackish cspt-btn-shape-rounded elementor-align-center e-transform cspt-btn-style-flat elementor-widget elementor-widget-button\" data-id=\"7b9c5ac\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scaleX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wilpowgroup.com\/index.php\/product-category\/copper-products\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1505f8a elementor-section-stretched cspt-col-stretched-none cspt-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1505f8a\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3409187 cspt-bg-color-over-image\" data-id=\"3409187\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3837401 cspt-align-center elementor-widget elementor-widget-cspt_multiple_icon_heading\" data-id=\"3837401\" data-element_type=\"widget\" data-widget_type=\"cspt_multiple_icon_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"creativesplanet-element creativesplanet-element-miconheading cspt-element-miconheading-style-1 creativesplanet-element-viewtype-row-column\" data-show=\"3\" data-columns=\"4\" data-loop=\"false\" data-autoplay=\"false\" data-center=\"false\" data-nav=\"false\" data-dots=\"false\" data-autoplayspeed=\"1000\" data-margin=\"\"><div class=\"creativesplanet-element-inner\">\n\t\t<div class=\"cspt-ele-header-area\">\n\t\t\t\t<div class=\"cspt-heading-subheading center-align \"><h2 class=\"cspt-element-title\">\n\t\t\t\n\t\t\t\tOUR SERVICES\n\t\t\t\n\t\t\t<\/h2>\n\t\t<\/div>\t\t<\/div>\n\n\t\t<div class=\"cspt-element-posts-wrapper row multi-columns-row\">\n\n\t\t<div class=\"cspt-ele cspt-miconheading-ele col-md-6 col-lg-3 \"><div class=\"cspt-ihbox cspt-ihbox-style-1\"><div class=\"cspt-ihbox cspt-ihbox-style- \">\n\t<div class=\"cspt-ihbox-icon\"><div class=\"cspt-ihbox-icon-wrapper\"><i class=\"far fa-check-circle\"><\/i><\/div><\/div>\t<div class=\"cspt-ihbox-contents\">\n\t\t<h2 class=\"cspt-element-title\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\tIEC Code updation\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"cspt-heading-desc\">We do IEC Code updation<\/div>\t\t\t<\/div><!-- .cspt-ihbox-contents -->\n<\/div>\n<\/div><\/div><div class=\"cspt-ele cspt-miconheading-ele col-md-6 col-lg-3 \"><div class=\"cspt-ihbox cspt-ihbox-style-1\"><div class=\"cspt-ihbox cspt-ihbox-style- \">\n\t<div class=\"cspt-ihbox-icon\"><div class=\"cspt-ihbox-icon-wrapper\"><i class=\"far fa-check-circle\"><\/i><\/div><\/div>\t<div class=\"cspt-ihbox-contents\">\n\t\t<h2 class=\"cspt-element-title\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\tAd code registration\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"cspt-heading-desc\">Ad code registration services<\/div>\t\t\t<\/div><!-- .cspt-ihbox-contents -->\n<\/div>\n<\/div><\/div><div class=\"cspt-ele cspt-miconheading-ele col-md-6 col-lg-3 \"><div class=\"cspt-ihbox cspt-ihbox-style-1\"><div class=\"cspt-ihbox cspt-ihbox-style- \">\n\t<div class=\"cspt-ihbox-icon\"><div class=\"cspt-ihbox-icon-wrapper\"><i class=\"far fa-check-circle\"><\/i><\/div><\/div>\t<div class=\"cspt-ihbox-contents\">\n\t\t<h2 class=\"cspt-element-title\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\tCustom Clearance\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"cspt-heading-desc\">Custom Clearance in Chennai, Thoothukudi and Kochin Port<\/div>\t\t\t<\/div><!-- .cspt-ihbox-contents -->\n<\/div>\n<\/div><\/div><div class=\"cspt-ele cspt-miconheading-ele col-md-6 col-lg-3 \"><div class=\"cspt-ihbox cspt-ihbox-style-1\"><div class=\"cspt-ihbox cspt-ihbox-style- \">\n\t<div class=\"cspt-ihbox-icon\"><div class=\"cspt-ihbox-icon-wrapper\"><i class=\"far fa-check-circle\"><\/i><\/div><\/div>\t<div class=\"cspt-ihbox-contents\">\n\t\t<h2 class=\"cspt-element-title\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\tTransportation\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"cspt-heading-desc\">We provide transportation Services<\/div>\t\t\t<\/div><!-- .cspt-ihbox-contents -->\n<\/div>\n<\/div><\/div><div class=\"cspt-ele cspt-miconheading-ele col-md-6 col-lg-3 \"><div class=\"cspt-ihbox cspt-ihbox-style-1\"><div class=\"cspt-ihbox cspt-ihbox-style- \">\n\t<div class=\"cspt-ihbox-icon\"><div class=\"cspt-ihbox-icon-wrapper\"><i class=\"far fa-check-circle\"><\/i><\/div><\/div>\t<div class=\"cspt-ihbox-contents\">\n\t\t<h2 class=\"cspt-element-title\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\tCOO Registration\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"cspt-heading-desc\">We do COO Registration services<\/div>\t\t\t<\/div><!-- .cspt-ihbox-contents -->\n<\/div>\n<\/div><\/div><div class=\"cspt-ele cspt-miconheading-ele col-md-6 col-lg-3 \"><div class=\"cspt-ihbox cspt-ihbox-style-1\"><div class=\"cspt-ihbox cspt-ihbox-style- \">\n\t<div class=\"cspt-ihbox-icon\"><div class=\"cspt-ihbox-icon-wrapper\"><i class=\"far fa-check-circle\"><\/i><\/div><\/div>\t<div class=\"cspt-ihbox-contents\">\n\t\t<h2 class=\"cspt-element-title\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\tIcegate Registration\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"cspt-heading-desc\">We help you to do icegate registration<\/div>\t\t\t<\/div><!-- .cspt-ihbox-contents -->\n<\/div>\n<\/div><\/div><div class=\"cspt-ele cspt-miconheading-ele col-md-6 col-lg-3 \"><div class=\"cspt-ihbox cspt-ihbox-style-1\"><div class=\"cspt-ihbox cspt-ihbox-style- \">\n\t<div class=\"cspt-ihbox-icon\"><div class=\"cspt-ihbox-icon-wrapper\"><i class=\"far fa-check-circle\"><\/i><\/div><\/div>\t<div class=\"cspt-ihbox-contents\">\n\t\t<h2 class=\"cspt-element-title\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\tFrieght Forwarding\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"cspt-heading-desc\">Wilpo Group provides fright forwarding services<\/div>\t\t\t<\/div><!-- .cspt-ihbox-contents -->\n<\/div>\n<\/div><\/div><div class=\"cspt-ele cspt-miconheading-ele col-md-6 col-lg-3 \"><div class=\"cspt-ihbox cspt-ihbox-style-1\"><div class=\"cspt-ihbox cspt-ihbox-style- \">\n\t<div class=\"cspt-ihbox-icon\"><div class=\"cspt-ihbox-icon-wrapper\"><i class=\"far fa-check-circle\"><\/i><\/div><\/div>\t<div class=\"cspt-ihbox-contents\">\n\t\t<h2 class=\"cspt-element-title\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\tDGFT License\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"cspt-heading-desc\">We help you for DGFT Licensing<\/div>\t\t\t<\/div><!-- .cspt-ihbox-contents -->\n<\/div>\n<\/div><\/div><div class=\"cspt-ele cspt-miconheading-ele col-md-6 col-lg-3 \"><div class=\"cspt-ihbox cspt-ihbox-style-1\"><div class=\"cspt-ihbox cspt-ihbox-style- \">\n\t<div class=\"cspt-ihbox-icon\"><div class=\"cspt-ihbox-icon-wrapper\"><i class=\"far fa-check-circle\"><\/i><\/div><\/div>\t<div class=\"cspt-ihbox-contents\">\n\t\t<h2 class=\"cspt-element-title\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\tGST Filing &amp; Registration\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t<div class=\"cspt-heading-desc\">We provide professional GST filing &amp; registration services.<\/div>\t\t\t<\/div><!-- .cspt-ihbox-contents -->\n<\/div>\n<\/div><\/div>\n\t\t<\/div>\n\n\t\t<\/div><!-- .creativesplanet-element-inner -->   <\/div><!-- .creativesplanet-element -->  \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-57b798a2 cspt-col-stretched-left elementor-section-stretched cspt-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"57b798a2\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-5744786f cspt-bg-color-over-image\" data-id=\"5744786f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7dd39984 elementor-widget elementor-widget-spacer\" data-id=\"7dd39984\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-39708881 cspt-bg-color-yes cspt-elementor-bg-color-globalcolor cspt-text-color-white cspt-bg-color-over-image\" data-id=\"39708881\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-743d5869 cspt-align-left elementor-widget elementor-widget-cspt_heading\" data-id=\"743d5869\" data-element_type=\"widget\" data-widget_type=\"cspt_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t<div class=\"cspt-heading-subheading left-align cspt-reverse-heading-yes\"><h4 class=\"cspt-element-subtitle\">\n\t\t\t\n\t\t\t\tOUR STORY\n\t\t\t\n\t\t\t<\/h4>\n\t\t<h2 class=\"cspt-element-title\">\n\t\t\t\n\t\t\t\tBest Solution for Your Needs!\n\t\t\t\n\t\t\t<\/h2>\n\t\t<div class=\"cspt-heading-desc\">Welcome to Wilpow Group! Thank you for your interest in our company.\n\nWilpow Group has successfully carved its own path, establishing a strong reputation and name for itself in the market. As prominent exporters, we take pride in offering a wide array of exquisite products, including Wooden Handicrafts, Wooden Items, Glass Items, Handmade Products, Photo Frames, Handmade Clothing, Decorative Products, and an impressive variety of Wooden Temples.\n\nOur products epitomize elegance, style, and superior quality, setting them apart in the industry. With a well-established global clientele, we have earned the trust of customers worldwide.<\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66cb0e28 cspt-btn-color-white cspt-btn-shape-round cspt-btn-style-flat elementor-widget elementor-widget-button\" data-id=\"66cb0e28\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18abb6eb cspt-bg-color-yes cspt-elementor-bg-color-light elementor-section-stretched cspt-col-stretched-none cspt-bg-color-over-image elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18abb6eb\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-26bd3fcd cspt-bg-color-over-image\" data-id=\"26bd3fcd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7060fb1d elementor-widget elementor-widget-cspt_testimonial_element\" data-id=\"7060fb1d\" data-element_type=\"widget\" data-widget_type=\"cspt_testimonial_element.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"creativesplanet-element creativesplanet-element-testimonial cspt-element-testimonial-style-4 creativesplanet-element-viewtype-carousel creativesplanet-gap-30px\" data-show=\"3\" data-columns=\"3\" data-loop=\"false\" data-autoplay=\"false\" data-center=\"false\" data-nav=\"false\" data-dots=\"true\" data-autoplayspeed=\"1000\" data-margin=\"30px\"><div class=\"creativesplanet-element-inner\">\n\t\t\n\t\t\n\t\t<\/div><!-- .creativesplanet-element-inner -->   <\/div><!-- .creativesplanet-element -->  \n\t    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Export Welcome to our world of exporting top-quality products worldwide. If you seek the best products delivered on time, you&#8217;ve come to the right place! Import agent (for foreign client) We help foreign company to introduce his best quality product in India and help them to find local partners in India Sourcing Agent We are working as local partner of our foreign client to source best quality product from India[&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-80","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/wilpowgroup.com\/index.php\/wp-json\/wp\/v2\/pages\/80","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wilpowgroup.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wilpowgroup.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wilpowgroup.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wilpowgroup.com\/index.php\/wp-json\/wp\/v2\/comments?post=80"}],"version-history":[{"count":251,"href":"https:\/\/wilpowgroup.com\/index.php\/wp-json\/wp\/v2\/pages\/80\/revisions"}],"predecessor-version":[{"id":912,"href":"https:\/\/wilpowgroup.com\/index.php\/wp-json\/wp\/v2\/pages\/80\/revisions\/912"}],"wp:attachment":[{"href":"https:\/\/wilpowgroup.com\/index.php\/wp-json\/wp\/v2\/media?parent=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}